{"id":2003,"date":"2020-12-15T19:19:02","date_gmt":"2020-12-16T01:19:02","guid":{"rendered":"http:\/\/www.elmiradordequetzales.com\/demo\/tour-de-quetzal\/"},"modified":"2024-04-29T15:55:54","modified_gmt":"2024-04-29T21:55:54","slug":"quetzals-tour","status":"publish","type":"page","link":"https:\/\/www.elmiradordequetzales.com\/en\/tours\/quetzals-tour\/","title":{"rendered":"Quetzal\u2019s Tour"},"content":{"rendered":"<div id=\"pl-2003\"  class=\"panel-layout\" ><div id=\"pg-2003-0\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-2003-0-0\"  class=\"panel-grid-cell\" ><div id=\"panel-2003-0-0-0\" class=\"so-panel widget widget_sow-slider panel-first-child\" data-index=\"0\" ><div class=\"so-widget-sow-slider so-widget-sow-slider-default-53fd0f98de19-2003\"><div class=\"sow-slider-base\" style=\"display: none\"><ul class=\"sow-slider-images\" data-settings=\"{&quot;pagination&quot;:true,&quot;speed&quot;:800,&quot;timeout&quot;:8000,&quot;paused&quot;:false,&quot;pause_on_hover&quot;:false,&quot;swipe&quot;:true,&quot;nav_always_show_desktop&quot;:&quot;&quot;,&quot;nav_always_show_mobile&quot;:&quot;&quot;,&quot;breakpoint&quot;:&quot;780px&quot;,&quot;unmute&quot;:false}\">\t\t<li class=\"sow-slider-image  sow-slider-image-cover\" style=\"background-image: url(https:\/\/www.elmiradordequetzales.com\/wp-content\/uploads\/2021\/05\/quetzales-tour-1.jpg)\" >\n\t\t\t\t\t\t\t\t\t<img width=\"1170\" height=\"553\" src=\"https:\/\/www.elmiradordequetzales.com\/wp-content\/uploads\/2021\/05\/quetzales-tour-1.jpg\" class=\"sow-slider-background-image skip-lazy\" alt=\"\" loading=\"eager\" srcset=\"https:\/\/www.elmiradordequetzales.com\/wp-content\/uploads\/2021\/05\/quetzales-tour-1.jpg 1170w, https:\/\/www.elmiradordequetzales.com\/wp-content\/uploads\/2021\/05\/quetzales-tour-1-300x142.jpg 300w, https:\/\/www.elmiradordequetzales.com\/wp-content\/uploads\/2021\/05\/quetzales-tour-1-1024x484.jpg 1024w, https:\/\/www.elmiradordequetzales.com\/wp-content\/uploads\/2021\/05\/quetzales-tour-1-768x363.jpg 768w\" sizes=\"(max-width: 1170px) 100vw, 1170px\" \/>\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t<li class=\"sow-slider-image  sow-slider-image-cover\" style=\"background-image: url(https:\/\/www.elmiradordequetzales.com\/wp-content\/uploads\/2021\/05\/quetzales-tour-2.jpg)\" >\n\t\t\t\t\t\t\t\t\t<img width=\"1170\" height=\"553\" src=\"https:\/\/www.elmiradordequetzales.com\/wp-content\/uploads\/2021\/05\/quetzales-tour-2.jpg\" class=\"sow-slider-background-image skip-lazy\" alt=\"\" loading=\"eager\" srcset=\"https:\/\/www.elmiradordequetzales.com\/wp-content\/uploads\/2021\/05\/quetzales-tour-2.jpg 1170w, https:\/\/www.elmiradordequetzales.com\/wp-content\/uploads\/2021\/05\/quetzales-tour-2-300x142.jpg 300w, https:\/\/www.elmiradordequetzales.com\/wp-content\/uploads\/2021\/05\/quetzales-tour-2-1024x484.jpg 1024w, https:\/\/www.elmiradordequetzales.com\/wp-content\/uploads\/2021\/05\/quetzales-tour-2-768x363.jpg 768w\" sizes=\"(max-width: 1170px) 100vw, 1170px\" \/>\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t<li class=\"sow-slider-image  sow-slider-image-cover\" style=\"background-image: url(https:\/\/www.elmiradordequetzales.com\/wp-content\/uploads\/2021\/05\/quetzales-tour-3.jpg)\" >\n\t\t\t\t\t\t\t\t\t<img width=\"1170\" height=\"553\" src=\"https:\/\/www.elmiradordequetzales.com\/wp-content\/uploads\/2021\/05\/quetzales-tour-3.jpg\" class=\"sow-slider-background-image skip-lazy\" alt=\"\" loading=\"eager\" srcset=\"https:\/\/www.elmiradordequetzales.com\/wp-content\/uploads\/2021\/05\/quetzales-tour-3.jpg 1170w, https:\/\/www.elmiradordequetzales.com\/wp-content\/uploads\/2021\/05\/quetzales-tour-3-300x142.jpg 300w, https:\/\/www.elmiradordequetzales.com\/wp-content\/uploads\/2021\/05\/quetzales-tour-3-1024x484.jpg 1024w, https:\/\/www.elmiradordequetzales.com\/wp-content\/uploads\/2021\/05\/quetzales-tour-3-768x363.jpg 768w\" sizes=\"(max-width: 1170px) 100vw, 1170px\" \/>\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t<li class=\"sow-slider-image  sow-slider-image-cover\" style=\"background-image: url(https:\/\/www.elmiradordequetzales.com\/wp-content\/uploads\/2021\/05\/quetzales-tour-4.jpg)\" >\n\t\t\t\t\t\t\t\t\t<img width=\"1170\" height=\"553\" src=\"https:\/\/www.elmiradordequetzales.com\/wp-content\/uploads\/2021\/05\/quetzales-tour-4.jpg\" class=\"sow-slider-background-image skip-lazy\" alt=\"\" loading=\"eager\" srcset=\"https:\/\/www.elmiradordequetzales.com\/wp-content\/uploads\/2021\/05\/quetzales-tour-4.jpg 1170w, https:\/\/www.elmiradordequetzales.com\/wp-content\/uploads\/2021\/05\/quetzales-tour-4-300x142.jpg 300w, https:\/\/www.elmiradordequetzales.com\/wp-content\/uploads\/2021\/05\/quetzales-tour-4-1024x484.jpg 1024w, https:\/\/www.elmiradordequetzales.com\/wp-content\/uploads\/2021\/05\/quetzales-tour-4-768x363.jpg 768w\" sizes=\"(max-width: 1170px) 100vw, 1170px\" \/>\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t<li class=\"sow-slider-image  sow-slider-image-cover\" style=\"background-image: url(https:\/\/www.elmiradordequetzales.com\/wp-content\/uploads\/2021\/05\/quetzales-tour-5.jpg)\" >\n\t\t\t\t\t\t\t\t\t<img width=\"1170\" height=\"553\" src=\"https:\/\/www.elmiradordequetzales.com\/wp-content\/uploads\/2021\/05\/quetzales-tour-5.jpg\" class=\"sow-slider-background-image skip-lazy\" alt=\"\" loading=\"eager\" srcset=\"https:\/\/www.elmiradordequetzales.com\/wp-content\/uploads\/2021\/05\/quetzales-tour-5.jpg 1170w, https:\/\/www.elmiradordequetzales.com\/wp-content\/uploads\/2021\/05\/quetzales-tour-5-300x142.jpg 300w, https:\/\/www.elmiradordequetzales.com\/wp-content\/uploads\/2021\/05\/quetzales-tour-5-1024x484.jpg 1024w, https:\/\/www.elmiradordequetzales.com\/wp-content\/uploads\/2021\/05\/quetzales-tour-5-768x363.jpg 768w\" sizes=\"(max-width: 1170px) 100vw, 1170px\" \/>\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t<li class=\"sow-slider-image  sow-slider-image-cover\" style=\"background-image: url(https:\/\/www.elmiradordequetzales.com\/wp-content\/uploads\/2021\/05\/quetzales-tour-6.jpg)\" >\n\t\t\t\t\t\t\t\t\t<img width=\"1170\" height=\"553\" src=\"https:\/\/www.elmiradordequetzales.com\/wp-content\/uploads\/2021\/05\/quetzales-tour-6.jpg\" class=\"sow-slider-background-image skip-lazy\" alt=\"\" loading=\"eager\" srcset=\"https:\/\/www.elmiradordequetzales.com\/wp-content\/uploads\/2021\/05\/quetzales-tour-6.jpg 1170w, https:\/\/www.elmiradordequetzales.com\/wp-content\/uploads\/2021\/05\/quetzales-tour-6-300x142.jpg 300w, https:\/\/www.elmiradordequetzales.com\/wp-content\/uploads\/2021\/05\/quetzales-tour-6-1024x484.jpg 1024w, https:\/\/www.elmiradordequetzales.com\/wp-content\/uploads\/2021\/05\/quetzales-tour-6-768x363.jpg 768w\" sizes=\"(max-width: 1170px) 100vw, 1170px\" \/>\t\t\t\t\t\t\t\t<\/li>\n\t\t<\/ul>\t\t\t\t<ol class=\"sow-slider-pagination\">\n\t\t\t\t\t\t\t\t\t\t\t<li><a href=\"#\" data-goto=\"0\" aria-label=\"display slide 1\"><\/a><\/li>\n\t\t\t\t\t\t\t\t\t\t\t<li><a href=\"#\" data-goto=\"1\" aria-label=\"display slide 2\"><\/a><\/li>\n\t\t\t\t\t\t\t\t\t\t\t<li><a href=\"#\" data-goto=\"2\" aria-label=\"display slide 3\"><\/a><\/li>\n\t\t\t\t\t\t\t\t\t\t\t<li><a href=\"#\" data-goto=\"3\" aria-label=\"display slide 4\"><\/a><\/li>\n\t\t\t\t\t\t\t\t\t\t\t<li><a href=\"#\" data-goto=\"4\" aria-label=\"display slide 5\"><\/a><\/li>\n\t\t\t\t\t\t\t\t\t\t\t<li><a href=\"#\" data-goto=\"5\" aria-label=\"display slide 6\"><\/a><\/li>\n\t\t\t\t\t\t\t\t\t<\/ol>\n\n\t\t\t\t<div class=\"sow-slide-nav sow-slide-nav-next\">\n\t\t\t\t\t<a href=\"#\" data-goto=\"next\" aria-label=\"next slide\" data-action=\"next\">\n\t\t\t\t\t\t<em class=\"sow-sld-icon-thin-right\"><\/em>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\n\t\t\t\t<div class=\"sow-slide-nav sow-slide-nav-prev\">\n\t\t\t\t\t<a href=\"#\" data-goto=\"previous\" aria-label=\"previous slide\" data-action=\"prev\">\n\t\t\t\t\t\t<em class=\"sow-sld-icon-thin-left\"><\/em>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div><\/div><\/div><div id=\"panel-2003-0-0-1\" class=\"so-panel widget widget_text panel-last-child\" data-index=\"1\" >\t\t\t<div class=\"textwidget\"><p>This tour is for the observation of one of the most beautiful birds in the world, the Quetzal. The visitor will be accompanied by a guide, who will be equipped with a telescope, binoculars, and a bird book, to facilitate the sighting and recognize it in the bird book. Normally this tour is recommended to do early in the morning.<\/p>\n<p>The sighting season in our area is from November to mid-June, in the other months of the year we must look for another site outside the property to guarantee observation.<\/p>\n<ul>\n<li><strong>Cost $35<\/strong>. Per person. At least 2 people. Duration 2 hours.<\/li>\n<li><strong>Cost $70<\/strong>. Per person. At least 2 people. Duration 2 hours. Private.<\/li>\n<li>The Quetzals tour includes the <strong>entrance fee<\/strong>.<\/li>\n<\/ul>\n<\/div>\n\t\t<\/div><\/div><\/div><div id=\"pg-2003-1\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-2003-1-0\"  class=\"panel-grid-cell\" ><div id=\"panel-2003-1-0-0\" class=\"so-panel widget widget_sow-button panel-first-child panel-last-child\" data-index=\"2\" ><div class=\"so-widget-sow-button so-widget-sow-button-atom-dd3ba6a7fbf5-2003\"><div class=\"ow-button-base ow-button-align-left\">\n\t<a href=\"#form\" class=\"ow-icon-placement-left ow-button-hover\" \t\t>\n\t\t<span>\n\t\t\t\n\t\t\tBOOK NOW\t\t<\/span>\n\t<\/a>\n<\/div>\n<\/div><\/div><\/div><div id=\"pgc-2003-1-1\"  class=\"panel-grid-cell\" ><div id=\"panel-2003-1-1-0\" class=\"so-panel widget widget_sow-button panel-first-child panel-last-child\" data-index=\"3\" ><div class=\"so-widget-sow-button so-widget-sow-button-atom-dd3ba6a7fbf5-2003\"><div class=\"ow-button-base ow-button-align-left\">\n\t<a href=\"\/en\/rooms\/\" class=\"ow-icon-placement-left ow-button-hover\" \t\t>\n\t\t<span>\n\t\t\t\n\t\t\tOUR BUNGALOWS\t\t<\/span>\n\t<\/a>\n<\/div>\n<\/div><\/div><\/div><div id=\"pgc-2003-1-2\"  class=\"panel-grid-cell panel-grid-cell-empty panel-grid-cell-mobile-last\" ><\/div><div id=\"pgc-2003-1-3\"  class=\"panel-grid-cell panel-grid-cell-empty\" ><\/div><\/div><div id=\"pg-2003-2\"  class=\"panel-grid panel-has-style\" ><div class=\"so-parallax siteorigin-panels-stretch panel-row-style panel-row-style-for-2003-2\" data-stretch-type=\"full\" ><img width=\"1920\" height=\"1109\" src=\"https:\/\/www.elmiradordequetzales.com\/wp-content\/uploads\/2020\/12\/bg-caracteristicas-quetzal.jpg\" class=\"attachment-full size-full\" alt=\"\" loading=\"eager\" data-siteorigin-parallax=\"true\" srcset=\"https:\/\/www.elmiradordequetzales.com\/wp-content\/uploads\/2020\/12\/bg-caracteristicas-quetzal.jpg 1920w, https:\/\/www.elmiradordequetzales.com\/wp-content\/uploads\/2020\/12\/bg-caracteristicas-quetzal-300x173.jpg 300w, https:\/\/www.elmiradordequetzales.com\/wp-content\/uploads\/2020\/12\/bg-caracteristicas-quetzal-1024x591.jpg 1024w, https:\/\/www.elmiradordequetzales.com\/wp-content\/uploads\/2020\/12\/bg-caracteristicas-quetzal-768x444.jpg 768w, https:\/\/www.elmiradordequetzales.com\/wp-content\/uploads\/2020\/12\/bg-caracteristicas-quetzal-1536x887.jpg 1536w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/><div id=\"pgc-2003-2-0\"  class=\"panel-grid-cell\" ><div id=\"panel-2003-2-0-0\" class=\"so-panel widget widget_sow-features panel-first-child panel-last-child\" data-index=\"4\" ><div class=\"panel-widget-style panel-widget-style-for-2003-2-0-0\" ><div class=\"so-widget-sow-features so-widget-sow-features-default-a6ed224f5f16-2003\">\n<div class=\"sow-features-list sow-features-responsive\">\n\n\t\t\t\n\t\t\t<div class=\"sow-features-feature sow-icon-container-position-top sow-features-feature-last-row\" style=\"width: 25%\">\n\n\t\t\t\t\t\t\t\t<div\n\t\t\t\t\tclass=\"sow-icon-container sow-container-none\"\n                    style=\"color: #404040; \"\n\t\t\t\t\t>\n\t\t\t\t\t<div class=\"sow-icon-image\" style=\"background-image: url(https:\/\/www.elmiradordequetzales.com\/wp-content\/uploads\/2020\/12\/icono01-b.png); font-size: 70px\"><\/div>\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<div class=\"textwidget\">\n\t\t\t\t\t\t\t\t\t\t\t<h2>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\tMinimun 2 persons\t\t\t\t\t\t\t\t\t\t\t\t\t<\/h2>\n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\n\t\t\n\t\t\t<div class=\"sow-features-feature sow-icon-container-position-top sow-features-feature-last-row\" style=\"width: 25%\">\n\n\t\t\t\t\t\t\t\t<div\n\t\t\t\t\tclass=\"sow-icon-container sow-container-none\"\n                    style=\"color: #404040; \"\n\t\t\t\t\t>\n\t\t\t\t\t<div class=\"sow-icon-image\" style=\"background-image: url(https:\/\/www.elmiradordequetzales.com\/wp-content\/uploads\/2020\/12\/icono02-b.png); font-size: 70px\"><\/div>\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<div class=\"textwidget\">\n\t\t\t\t\t\t\t\t\t\t\t<h2>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\tDuration 2 hours\t\t\t\t\t\t\t\t\t\t\t\t\t<\/h2>\n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\n\t\t\n\t\t\t<div class=\"sow-features-feature sow-icon-container-position-top sow-features-feature-last-row\" style=\"width: 25%\">\n\n\t\t\t\t\t\t\t\t<div\n\t\t\t\t\tclass=\"sow-icon-container sow-container-none\"\n                    style=\"color: #404040; \"\n\t\t\t\t\t>\n\t\t\t\t\t<div class=\"sow-icon-image\" style=\"background-image: url(https:\/\/www.elmiradordequetzales.com\/wp-content\/uploads\/2020\/12\/icono03-b.png); font-size: 70px\"><\/div>\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<div class=\"textwidget\">\n\t\t\t\t\t\t\t\t\t\t\t<h2>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\tTour difficulty, moderate\t\t\t\t\t\t\t\t\t\t\t\t\t<\/h2>\n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\n\t\t\n\t\t\t<div class=\"sow-features-feature sow-icon-container-position-top sow-features-feature-last-row\" style=\"width: 25%\">\n\n\t\t\t\t\t\t\t\t<div\n\t\t\t\t\tclass=\"sow-icon-container sow-container-none\"\n                    style=\"color: #404040; \"\n\t\t\t\t\t>\n\t\t\t\t\t<div class=\"sow-icon-image\" style=\"background-image: url(https:\/\/www.elmiradordequetzales.com\/wp-content\/uploads\/2020\/12\/icono04-b.png); font-size: 70px\"><\/div>\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<div class=\"textwidget\">\n\t\t\t\t\t\t\t\t\t\t\t<h2>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\tFor all ages\t\t\t\t\t\t\t\t\t\t\t\t\t<\/h2>\n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\n<\/div>\n<\/div><\/div><\/div><\/div><\/div><\/div><div id=\"pg-2003-3\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-2003-3-0\"  class=\"panel-grid-cell\" ><div id=\"panel-2003-3-0-0\" class=\"so-panel widget widget_sow-editor panel-first-child\" data-index=\"5\" ><div class=\"so-widget-sow-editor so-widget-sow-editor-base\">\n<div class=\"siteorigin-widget-tinymce textwidget\">\n\t<h2 style=\"text-align: center;\">Gallery<\/h2>\n<p style=\"text-align: center;\">Image gallery of our Quetzal\u2019s Tour, book with us and see them in their habitat, it is a wonderful experience.<\/p>\n<\/div>\n<\/div><\/div><div id=\"panel-2003-3-0-1\" class=\"so-panel widget widget_media_gallery panel-last-child\" data-index=\"6\" ><div id='gallery-1' class='gallery galleryid-2003 gallery-columns-4 gallery-size-medium'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/www.elmiradordequetzales.com\/wp-content\/uploads\/2020\/12\/Quetzal-16.jpg'><img width=\"225\" height=\"300\" src=\"https:\/\/www.elmiradordequetzales.com\/wp-content\/uploads\/2020\/12\/Quetzal-16-225x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.elmiradordequetzales.com\/wp-content\/uploads\/2020\/12\/Quetzal-16-225x300.jpg 225w, https:\/\/www.elmiradordequetzales.com\/wp-content\/uploads\/2020\/12\/Quetzal-16-768x1024.jpg 768w, https:\/\/www.elmiradordequetzales.com\/wp-content\/uploads\/2020\/12\/Quetzal-16.jpg 900w\" sizes=\"(max-width: 225px) 100vw, 225px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/www.elmiradordequetzales.com\/wp-content\/uploads\/2020\/12\/Quetzal-15.jpg'><img width=\"166\" height=\"300\" src=\"https:\/\/www.elmiradordequetzales.com\/wp-content\/uploads\/2020\/12\/Quetzal-15-166x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.elmiradordequetzales.com\/wp-content\/uploads\/2020\/12\/Quetzal-15-166x300.jpg 166w, https:\/\/www.elmiradordequetzales.com\/wp-content\/uploads\/2020\/12\/Quetzal-15-566x1024.jpg 566w, https:\/\/www.elmiradordequetzales.com\/wp-content\/uploads\/2020\/12\/Quetzal-15-768x1390.jpg 768w, https:\/\/www.elmiradordequetzales.com\/wp-content\/uploads\/2020\/12\/Quetzal-15-849x1536.jpg 849w, https:\/\/www.elmiradordequetzales.com\/wp-content\/uploads\/2020\/12\/Quetzal-15.jpg 900w\" sizes=\"(max-width: 166px) 100vw, 166px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/www.elmiradordequetzales.com\/wp-content\/uploads\/2020\/12\/Quetzal-14.jpg'><img width=\"240\" height=\"300\" src=\"https:\/\/www.elmiradordequetzales.com\/wp-content\/uploads\/2020\/12\/Quetzal-14-240x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.elmiradordequetzales.com\/wp-content\/uploads\/2020\/12\/Quetzal-14-240x300.jpg 240w, https:\/\/www.elmiradordequetzales.com\/wp-content\/uploads\/2020\/12\/Quetzal-14-818x1024.jpg 818w, https:\/\/www.elmiradordequetzales.com\/wp-content\/uploads\/2020\/12\/Quetzal-14-768x962.jpg 768w, https:\/\/www.elmiradordequetzales.com\/wp-content\/uploads\/2020\/12\/Quetzal-14.jpg 900w\" sizes=\"(max-width: 240px) 100vw, 240px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/www.elmiradordequetzales.com\/wp-content\/uploads\/2020\/12\/Quetzal-13.jpg'><img width=\"165\" height=\"300\" src=\"https:\/\/www.elmiradordequetzales.com\/wp-content\/uploads\/2020\/12\/Quetzal-13-165x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.elmiradordequetzales.com\/wp-content\/uploads\/2020\/12\/Quetzal-13-165x300.jpg 165w, https:\/\/www.elmiradordequetzales.com\/wp-content\/uploads\/2020\/12\/Quetzal-13-563x1024.jpg 563w, https:\/\/www.elmiradordequetzales.com\/wp-content\/uploads\/2020\/12\/Quetzal-13-768x1397.jpg 768w, https:\/\/www.elmiradordequetzales.com\/wp-content\/uploads\/2020\/12\/Quetzal-13-844x1536.jpg 844w, https:\/\/www.elmiradordequetzales.com\/wp-content\/uploads\/2020\/12\/Quetzal-13.jpg 900w\" sizes=\"(max-width: 165px) 100vw, 165px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/www.elmiradordequetzales.com\/wp-content\/uploads\/2020\/12\/Quetzal-12.jpg'><img width=\"208\" height=\"300\" src=\"https:\/\/www.elmiradordequetzales.com\/wp-content\/uploads\/2020\/12\/Quetzal-12-208x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.elmiradordequetzales.com\/wp-content\/uploads\/2020\/12\/Quetzal-12-208x300.jpg 208w, https:\/\/www.elmiradordequetzales.com\/wp-content\/uploads\/2020\/12\/Quetzal-12-708x1024.jpg 708w, https:\/\/www.elmiradordequetzales.com\/wp-content\/uploads\/2020\/12\/Quetzal-12-768x1110.jpg 768w, https:\/\/www.elmiradordequetzales.com\/wp-content\/uploads\/2020\/12\/Quetzal-12.jpg 900w\" sizes=\"(max-width: 208px) 100vw, 208px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/www.elmiradordequetzales.com\/wp-content\/uploads\/2020\/12\/Quetzal-11.jpg'><img width=\"220\" height=\"300\" src=\"https:\/\/www.elmiradordequetzales.com\/wp-content\/uploads\/2020\/12\/Quetzal-11-220x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.elmiradordequetzales.com\/wp-content\/uploads\/2020\/12\/Quetzal-11-220x300.jpg 220w, https:\/\/www.elmiradordequetzales.com\/wp-content\/uploads\/2020\/12\/Quetzal-11-752x1024.jpg 752w, https:\/\/www.elmiradordequetzales.com\/wp-content\/uploads\/2020\/12\/Quetzal-11-768x1046.jpg 768w, https:\/\/www.elmiradordequetzales.com\/wp-content\/uploads\/2020\/12\/Quetzal-11-270x370.jpg 270w, https:\/\/www.elmiradordequetzales.com\/wp-content\/uploads\/2020\/12\/Quetzal-11.jpg 900w\" sizes=\"(max-width: 220px) 100vw, 220px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.elmiradordequetzales.com\/wp-content\/uploads\/2020\/12\/Quetzal-10.jpg'><img width=\"300\" height=\"142\" src=\"https:\/\/www.elmiradordequetzales.com\/wp-content\/uploads\/2020\/12\/Quetzal-10-300x142.jpg\" class=\"attachment-medium size-medium\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.elmiradordequetzales.com\/wp-content\/uploads\/2020\/12\/Quetzal-10-300x142.jpg 300w, https:\/\/www.elmiradordequetzales.com\/wp-content\/uploads\/2020\/12\/Quetzal-10-1024x486.jpg 1024w, https:\/\/www.elmiradordequetzales.com\/wp-content\/uploads\/2020\/12\/Quetzal-10-768x364.jpg 768w, https:\/\/www.elmiradordequetzales.com\/wp-content\/uploads\/2020\/12\/Quetzal-10.jpg 1200w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.elmiradordequetzales.com\/wp-content\/uploads\/2020\/12\/Quetzal-9.jpg'><img width=\"300\" height=\"285\" src=\"https:\/\/www.elmiradordequetzales.com\/wp-content\/uploads\/2020\/12\/Quetzal-9-300x285.jpg\" class=\"attachment-medium size-medium\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.elmiradordequetzales.com\/wp-content\/uploads\/2020\/12\/Quetzal-9-300x285.jpg 300w, https:\/\/www.elmiradordequetzales.com\/wp-content\/uploads\/2020\/12\/Quetzal-9-768x730.jpg 768w, https:\/\/www.elmiradordequetzales.com\/wp-content\/uploads\/2020\/12\/Quetzal-9.jpg 900w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/www.elmiradordequetzales.com\/wp-content\/uploads\/2020\/12\/Quetzal-8.jpg'><img width=\"225\" height=\"300\" src=\"https:\/\/www.elmiradordequetzales.com\/wp-content\/uploads\/2020\/12\/Quetzal-8-225x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.elmiradordequetzales.com\/wp-content\/uploads\/2020\/12\/Quetzal-8-225x300.jpg 225w, https:\/\/www.elmiradordequetzales.com\/wp-content\/uploads\/2020\/12\/Quetzal-8-768x1024.jpg 768w, https:\/\/www.elmiradordequetzales.com\/wp-content\/uploads\/2020\/12\/Quetzal-8.jpg 900w\" sizes=\"(max-width: 225px) 100vw, 225px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/www.elmiradordequetzales.com\/wp-content\/uploads\/2020\/12\/Quetzal-7.jpg'><img width=\"185\" height=\"300\" src=\"https:\/\/www.elmiradordequetzales.com\/wp-content\/uploads\/2020\/12\/Quetzal-7-185x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.elmiradordequetzales.com\/wp-content\/uploads\/2020\/12\/Quetzal-7-185x300.jpg 185w, https:\/\/www.elmiradordequetzales.com\/wp-content\/uploads\/2020\/12\/Quetzal-7-633x1024.jpg 633w, https:\/\/www.elmiradordequetzales.com\/wp-content\/uploads\/2020\/12\/Quetzal-7-768x1242.jpg 768w, https:\/\/www.elmiradordequetzales.com\/wp-content\/uploads\/2020\/12\/Quetzal-7.jpg 900w\" sizes=\"(max-width: 185px) 100vw, 185px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/www.elmiradordequetzales.com\/wp-content\/uploads\/2020\/12\/Quetzal-6.jpg'><img width=\"203\" height=\"300\" src=\"https:\/\/www.elmiradordequetzales.com\/wp-content\/uploads\/2020\/12\/Quetzal-6-203x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.elmiradordequetzales.com\/wp-content\/uploads\/2020\/12\/Quetzal-6-203x300.jpg 203w, https:\/\/www.elmiradordequetzales.com\/wp-content\/uploads\/2020\/12\/Quetzal-6-693x1024.jpg 693w, https:\/\/www.elmiradordequetzales.com\/wp-content\/uploads\/2020\/12\/Quetzal-6-768x1135.jpg 768w, https:\/\/www.elmiradordequetzales.com\/wp-content\/uploads\/2020\/12\/Quetzal-6.jpg 900w\" sizes=\"(max-width: 203px) 100vw, 203px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/www.elmiradordequetzales.com\/wp-content\/uploads\/2020\/12\/Quetzal-5.jpg'><img width=\"221\" height=\"300\" src=\"https:\/\/www.elmiradordequetzales.com\/wp-content\/uploads\/2020\/12\/Quetzal-5-221x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.elmiradordequetzales.com\/wp-content\/uploads\/2020\/12\/Quetzal-5-221x300.jpg 221w, https:\/\/www.elmiradordequetzales.com\/wp-content\/uploads\/2020\/12\/Quetzal-5-754x1024.jpg 754w, https:\/\/www.elmiradordequetzales.com\/wp-content\/uploads\/2020\/12\/Quetzal-5-768x1043.jpg 768w, https:\/\/www.elmiradordequetzales.com\/wp-content\/uploads\/2020\/12\/Quetzal-5.jpg 900w\" sizes=\"(max-width: 221px) 100vw, 221px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/www.elmiradordequetzales.com\/wp-content\/uploads\/2020\/12\/Quetzal-4.jpg'><img width=\"196\" height=\"300\" src=\"https:\/\/www.elmiradordequetzales.com\/wp-content\/uploads\/2020\/12\/Quetzal-4-196x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.elmiradordequetzales.com\/wp-content\/uploads\/2020\/12\/Quetzal-4-196x300.jpg 196w, https:\/\/www.elmiradordequetzales.com\/wp-content\/uploads\/2020\/12\/Quetzal-4-667x1024.jpg 667w, https:\/\/www.elmiradordequetzales.com\/wp-content\/uploads\/2020\/12\/Quetzal-4-768x1178.jpg 768w, https:\/\/www.elmiradordequetzales.com\/wp-content\/uploads\/2020\/12\/Quetzal-4.jpg 900w\" sizes=\"(max-width: 196px) 100vw, 196px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/www.elmiradordequetzales.com\/wp-content\/uploads\/2020\/12\/Quetzal-3.jpg'><img width=\"165\" height=\"300\" src=\"https:\/\/www.elmiradordequetzales.com\/wp-content\/uploads\/2020\/12\/Quetzal-3-165x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.elmiradordequetzales.com\/wp-content\/uploads\/2020\/12\/Quetzal-3-165x300.jpg 165w, https:\/\/www.elmiradordequetzales.com\/wp-content\/uploads\/2020\/12\/Quetzal-3-564x1024.jpg 564w, https:\/\/www.elmiradordequetzales.com\/wp-content\/uploads\/2020\/12\/Quetzal-3-768x1395.jpg 768w, https:\/\/www.elmiradordequetzales.com\/wp-content\/uploads\/2020\/12\/Quetzal-3-846x1536.jpg 846w, https:\/\/www.elmiradordequetzales.com\/wp-content\/uploads\/2020\/12\/Quetzal-3.jpg 900w\" sizes=\"(max-width: 165px) 100vw, 165px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.elmiradordequetzales.com\/wp-content\/uploads\/2020\/12\/Quetzal-2.jpg'><img width=\"300\" height=\"271\" src=\"https:\/\/www.elmiradordequetzales.com\/wp-content\/uploads\/2020\/12\/Quetzal-2-300x271.jpg\" class=\"attachment-medium size-medium\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.elmiradordequetzales.com\/wp-content\/uploads\/2020\/12\/Quetzal-2-300x271.jpg 300w, https:\/\/www.elmiradordequetzales.com\/wp-content\/uploads\/2020\/12\/Quetzal-2-768x693.jpg 768w, https:\/\/www.elmiradordequetzales.com\/wp-content\/uploads\/2020\/12\/Quetzal-2.jpg 1024w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/www.elmiradordequetzales.com\/wp-content\/uploads\/2020\/12\/Quetzal-1.jpg'><img width=\"206\" height=\"300\" src=\"https:\/\/www.elmiradordequetzales.com\/wp-content\/uploads\/2020\/12\/Quetzal-1-206x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.elmiradordequetzales.com\/wp-content\/uploads\/2020\/12\/Quetzal-1-206x300.jpg 206w, https:\/\/www.elmiradordequetzales.com\/wp-content\/uploads\/2020\/12\/Quetzal-1-705x1024.jpg 705w, https:\/\/www.elmiradordequetzales.com\/wp-content\/uploads\/2020\/12\/Quetzal-1-768x1116.jpg 768w, https:\/\/www.elmiradordequetzales.com\/wp-content\/uploads\/2020\/12\/Quetzal-1.jpg 900w\" sizes=\"(max-width: 206px) 100vw, 206px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.elmiradordequetzales.com\/wp-content\/uploads\/2021\/05\/tour-quetzales1.jpeg'><img width=\"300\" height=\"226\" src=\"https:\/\/www.elmiradordequetzales.com\/wp-content\/uploads\/2021\/05\/tour-quetzales1-300x226.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.elmiradordequetzales.com\/wp-content\/uploads\/2021\/05\/tour-quetzales1-300x226.jpeg 300w, https:\/\/www.elmiradordequetzales.com\/wp-content\/uploads\/2021\/05\/tour-quetzales1.jpeg 640w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.elmiradordequetzales.com\/wp-content\/uploads\/2021\/05\/tour-quetzales1.jpg'><img width=\"300\" height=\"225\" src=\"https:\/\/www.elmiradordequetzales.com\/wp-content\/uploads\/2021\/05\/tour-quetzales1-300x225.jpg\" class=\"attachment-medium size-medium\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.elmiradordequetzales.com\/wp-content\/uploads\/2021\/05\/tour-quetzales1-300x225.jpg 300w, https:\/\/www.elmiradordequetzales.com\/wp-content\/uploads\/2021\/05\/tour-quetzales1.jpg 640w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.elmiradordequetzales.com\/wp-content\/uploads\/2021\/05\/tour-quetzales2.jpeg'><img width=\"300\" height=\"226\" src=\"https:\/\/www.elmiradordequetzales.com\/wp-content\/uploads\/2021\/05\/tour-quetzales2-300x226.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.elmiradordequetzales.com\/wp-content\/uploads\/2021\/05\/tour-quetzales2-300x226.jpeg 300w, https:\/\/www.elmiradordequetzales.com\/wp-content\/uploads\/2021\/05\/tour-quetzales2.jpeg 640w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.elmiradordequetzales.com\/wp-content\/uploads\/2021\/05\/tour-quetzales3.jpeg'><img width=\"300\" height=\"225\" src=\"https:\/\/www.elmiradordequetzales.com\/wp-content\/uploads\/2021\/05\/tour-quetzales3-300x225.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.elmiradordequetzales.com\/wp-content\/uploads\/2021\/05\/tour-quetzales3-300x225.jpeg 300w, https:\/\/www.elmiradordequetzales.com\/wp-content\/uploads\/2021\/05\/tour-quetzales3.jpeg 640w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.elmiradordequetzales.com\/wp-content\/uploads\/2021\/05\/tour-quetzales4.jpeg'><img width=\"300\" height=\"225\" src=\"https:\/\/www.elmiradordequetzales.com\/wp-content\/uploads\/2021\/05\/tour-quetzales4-300x225.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.elmiradordequetzales.com\/wp-content\/uploads\/2021\/05\/tour-quetzales4-300x225.jpeg 300w, https:\/\/www.elmiradordequetzales.com\/wp-content\/uploads\/2021\/05\/tour-quetzales4-768x576.jpeg 768w, https:\/\/www.elmiradordequetzales.com\/wp-content\/uploads\/2021\/05\/tour-quetzales4.jpeg 800w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n<\/div><\/div><\/div><div id=\"pg-2003-4\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-2003-4-0\"  class=\"panel-grid-cell\" ><div id=\"panel-2003-4-0-0\" class=\"widget_text so-panel widget widget_custom_html panel-first-child panel-last-child\" data-index=\"7\" ><div class=\"textwidget custom-html-widget\">\n<div role=\"form\" class=\"wpcf7\" id=\"wpcf7-f2079-o1\" lang=\"en-US\" dir=\"ltr\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/en\/wp-json\/wp\/v2\/pages\/2003#wpcf7-f2079-o1\" method=\"post\" class=\"wpcf7-form init\" novalidate=\"novalidate\" data-status=\"init\">\n<div style=\"display: none;\">\n<input type=\"hidden\" name=\"_wpcf7\" value=\"2079\" \/>\n<input type=\"hidden\" name=\"_wpcf7_version\" value=\"5.5.3\" \/>\n<input type=\"hidden\" name=\"_wpcf7_locale\" value=\"en_US\" \/>\n<input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f2079-o1\" \/>\n<input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/>\n<input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<\/div>\n<div class=\"formulario\" id=\"form\">\n<h2 style=\"text-align: center\">Reservation form<\/h2>\n<p style=\"text-align: center; margin-bottom: 30px\">You want to live the experience of this tour, send us your information to be contacted by our guides.  <\/p>\n<div class=\"form-section-1\">\n<label> Full name<br \/>\n    <span class=\"wpcf7-form-control-wrap your-name\"><input type=\"text\" name=\"your-name\" value=\"\" size=\"40\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" \/><\/span> <\/label>\n<\/div>\n<div class=\"form-section-2\">\n<label class=\"espacio\"> Email<br \/>\n    <span class=\"wpcf7-form-control-wrap your-email\"><input type=\"email\" name=\"your-email\" value=\"\" size=\"40\" class=\"wpcf7-form-control wpcf7-text wpcf7-email wpcf7-validates-as-required wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" \/><\/span> <\/label>\n<\/div>\n<div class=\"form-section-1\">\n<label> Phone<br \/>\n    <span class=\"wpcf7-form-control-wrap your-phone\"><input type=\"text\" name=\"your-phone\" value=\"\" size=\"40\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" \/><\/span> <\/label>\n<\/div>\n<div class=\"form-section-2\">\n<label> Estimated date:<br \/>\n    <span class=\"wpcf7-form-control-wrap date1\"><input type=\"date\" name=\"date1\" value=\"\" class=\"wpcf7-form-control wpcf7-date wpcf7-validates-as-required wpcf7-validates-as-date\" min=\"2026-05-13\" aria-required=\"true\" aria-invalid=\"false\" \/><\/span> <\/label>\n<\/div>\n<div class=\"form-section-1\">\n<label> Number of adults:<br \/>\n    <span class=\"wpcf7-form-control-wrap adults\"><input type=\"number\" name=\"adults\" value=\"1\" class=\"wpcf7-form-control wpcf7-number wpcf7-validates-as-required wpcf7-validates-as-number\" min=\"1\" max=\"30\" aria-required=\"true\" aria-invalid=\"false\" \/><\/span> <\/label>\n<\/div>\n<div class=\"form-section-2\">\n<label> Number of children:<br \/>\n    <span class=\"wpcf7-form-control-wrap children\"><input type=\"number\" name=\"children\" value=\"1\" class=\"wpcf7-form-control wpcf7-number wpcf7-validates-as-required wpcf7-validates-as-number\" min=\"1\" max=\"30\" aria-required=\"true\" aria-invalid=\"false\" \/><\/span> <\/label>\n<\/div>\n<p><label> Important comments or observations<br \/>\n    <span class=\"wpcf7-form-control-wrap your-message\"><textarea name=\"your-message\" cols=\"40\" rows=\"10\" class=\"wpcf7-form-control wpcf7-textarea\" aria-invalid=\"false\"><\/textarea><\/span> <\/label><br \/>\n<span class=\"wpcf7-form-control-wrap kc_captcha\"><span class=\"wpcf7-form-control wpcf7-radio\"> \n    <span class=\"captcha-image\" >\n        <span class=\"cf7ic_instructions\">Please prove you are human by selecting the <span> Car<\/span>.<\/span><label><input type=\"radio\" name=\"kc_captcha\" value=\"kc_human\" \/><svg width=\"50\" height=\"50\" aria-hidden=\"true\" role=\"img\" xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\"><path fill=\"currentColor\" d=\"M500 168h-55l-8-21a127 127 0 00-120-83H195a127 127 0 00-120 83l-8 21H12c-8 0-14 8-11 16l8 24a12 12 0 0011 8h29a64 64 0 00-33 56v48c0 16 6 31 16 42v62c0 13 11 24 24 24h48c13 0 24-11 24-24v-40h256v40c0 13 11 24 24 24h48c13 0 24-11 24-24v-62c10-11 16-26 16-42v-48c0-24-13-45-33-56h29a12 12 0 0011-8l8-24c3-8-3-16-11-16zm-365 2c9-25 33-42 60-42h122c27 0 51 17 60 42l15 38H120l15-38zM88 328a32 32 0 010-64c18 0 48 30 48 48s-30 16-48 16zm336 0c-18 0-48 2-48-16s30-48 48-48 32 14 32 32-14 32-32 32z\"\/><\/svg><\/label><label><input type=\"radio\" name=\"kc_captcha\" value=\"bot\" \/><svg width=\"50\" height=\"50\" aria-hidden=\"true\" role=\"img\" xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 640 512\"><path fill=\"currentColor\" d=\"M624 352h-16V244c0-13-5-25-14-34L494 110c-9-9-21-14-34-14h-44V48c0-26-21-48-48-48H48C22 0 0 22 0 48v320c0 27 22 48 48 48h16a96 96 0 00192 0h128a96 96 0 00192 0h48c9 0 16-7 16-16v-32c0-9-7-16-16-16zM160 464a48 48 0 110-96 48 48 0 010 96zm320 0a48 48 0 110-96 48 48 0 010 96zm80-208H416V144h44l100 100v12z\"\/><\/svg><\/label><label><input type=\"radio\" name=\"kc_captcha\" value=\"bot\" \/><svg width=\"50\" height=\"50\" aria-hidden=\"true\" role=\"img\" xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 384 512\"><path fill=\"currentColor\" d=\"M377 375l-83-87h34c21 0 32-25 17-40l-82-88h33c21 0 32-25 18-40L210 8c-10-11-26-11-36 0L70 120c-14 15-3 40 18 40h33l-82 88c-15 15-4 40 17 40h34L7 375c-15 16-4 41 17 41h120c0 33-11 49-34 68-12 9-5 28 10 28h144c15 0 22-19 10-28-20-16-34-32-34-68h120c21 0 32-25 17-41z\"\/><\/svg><\/label>\n    <\/span>\n    <span style=\"display:none\">\n        <input type=\"text\" name=\"kc_honeypot\">\n    <\/span><\/span><\/span><br \/>\n<input type=\"submit\" value=\"Enviar\" class=\"wpcf7-form-control has-spinner wpcf7-submit\" \/>\n<\/div>\n<p style=\"display: none !important;\"><label>&#916;<textarea name=\"_wpcf7_ak_hp_textarea\" cols=\"45\" rows=\"8\" maxlength=\"100\"><\/textarea><\/label><input type=\"hidden\" id=\"ak_js\" name=\"_wpcf7_ak_js\" value=\"20\"\/><script>document.getElementById( \"ak_js\" ).setAttribute( \"value\", ( new Date() ).getTime() );<\/script><\/p><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div><\/form><\/div><\/div><\/div><\/div><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>This tour is for the observation of one of the most beautiful birds in the world, the Quetzal. The visitor will be accompanied by a guide, who will be equipped with a telescope, binoculars, and a bird book, to facilitate the sighting and recognize it in the bird book. Normally this tour is recommended to [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":2349,"parent":2031,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v17.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Quetzal observation tour San Gerardo de Dota - Costa Rica<\/title>\n<meta name=\"description\" content=\"Our quetzal\u2019s tour, is by far, your best choice to observe and enjoy the species considered by many, as the most beautiful bird in the world.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.elmiradordequetzales.com\/en\/tours\/quetzals-tour\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Quetzal observation tour San Gerardo de Dota - Costa Rica\" \/>\n<meta property=\"og:description\" content=\"Our quetzal\u2019s tour, is by far, your best choice to observe and enjoy the species considered by many, as the most beautiful bird in the world.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.elmiradordequetzales.com\/en\/tours\/quetzals-tour\/\" \/>\n<meta property=\"og:site_name\" content=\"El Mirador de Quetzales\" \/>\n<meta property=\"article:modified_time\" content=\"2024-04-29T21:55:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.elmiradordequetzales.com\/wp-content\/uploads\/2021\/10\/top-quetzal-title.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.elmiradordequetzales.com\/#website\",\"url\":\"https:\/\/www.elmiradordequetzales.com\/\",\"name\":\"El Mirador de Quetzales\",\"description\":\"B\\u00fangalos\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.elmiradordequetzales.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.elmiradordequetzales.com\/en\/tours\/quetzals-tour\/#primaryimage\",\"inLanguage\":\"en-US\",\"url\":\"https:\/\/www.elmiradordequetzales.com\/wp-content\/uploads\/2021\/10\/top-quetzal-title.jpg\",\"contentUrl\":\"https:\/\/www.elmiradordequetzales.com\/wp-content\/uploads\/2021\/10\/top-quetzal-title.jpg\",\"width\":1920,\"height\":400,\"caption\":\"Quetzal observation tour\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.elmiradordequetzales.com\/en\/tours\/quetzals-tour\/#webpage\",\"url\":\"https:\/\/www.elmiradordequetzales.com\/en\/tours\/quetzals-tour\/\",\"name\":\"Quetzal observation tour San Gerardo de Dota - Costa Rica\",\"isPartOf\":{\"@id\":\"https:\/\/www.elmiradordequetzales.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.elmiradordequetzales.com\/en\/tours\/quetzals-tour\/#primaryimage\"},\"datePublished\":\"2020-12-16T01:19:02+00:00\",\"dateModified\":\"2024-04-29T21:55:54+00:00\",\"description\":\"Our quetzal\\u2019s tour, is by far, your best choice to observe and enjoy the species considered by many, as the most beautiful bird in the world.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.elmiradordequetzales.com\/en\/tours\/quetzals-tour\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.elmiradordequetzales.com\/en\/tours\/quetzals-tour\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.elmiradordequetzales.com\/en\/tours\/quetzals-tour\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.elmiradordequetzales.com\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tours\",\"item\":\"https:\/\/www.elmiradordequetzales.com\/en\/tours\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Quetzal\\u2019s Tour\"}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Quetzal observation tour San Gerardo de Dota - Costa Rica","description":"Our quetzal\u2019s tour, is by far, your best choice to observe and enjoy the species considered by many, as the most beautiful bird in the world.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.elmiradordequetzales.com\/en\/tours\/quetzals-tour\/","og_locale":"en_US","og_type":"article","og_title":"Quetzal observation tour San Gerardo de Dota - Costa Rica","og_description":"Our quetzal\u2019s tour, is by far, your best choice to observe and enjoy the species considered by many, as the most beautiful bird in the world.","og_url":"https:\/\/www.elmiradordequetzales.com\/en\/tours\/quetzals-tour\/","og_site_name":"El Mirador de Quetzales","article_modified_time":"2024-04-29T21:55:54+00:00","og_image":[{"width":1920,"height":400,"url":"https:\/\/www.elmiradordequetzales.com\/wp-content\/uploads\/2021\/10\/top-quetzal-title.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/www.elmiradordequetzales.com\/#website","url":"https:\/\/www.elmiradordequetzales.com\/","name":"El Mirador de Quetzales","description":"B\u00fangalos","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.elmiradordequetzales.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"ImageObject","@id":"https:\/\/www.elmiradordequetzales.com\/en\/tours\/quetzals-tour\/#primaryimage","inLanguage":"en-US","url":"https:\/\/www.elmiradordequetzales.com\/wp-content\/uploads\/2021\/10\/top-quetzal-title.jpg","contentUrl":"https:\/\/www.elmiradordequetzales.com\/wp-content\/uploads\/2021\/10\/top-quetzal-title.jpg","width":1920,"height":400,"caption":"Quetzal observation tour"},{"@type":"WebPage","@id":"https:\/\/www.elmiradordequetzales.com\/en\/tours\/quetzals-tour\/#webpage","url":"https:\/\/www.elmiradordequetzales.com\/en\/tours\/quetzals-tour\/","name":"Quetzal observation tour San Gerardo de Dota - Costa Rica","isPartOf":{"@id":"https:\/\/www.elmiradordequetzales.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.elmiradordequetzales.com\/en\/tours\/quetzals-tour\/#primaryimage"},"datePublished":"2020-12-16T01:19:02+00:00","dateModified":"2024-04-29T21:55:54+00:00","description":"Our quetzal\u2019s tour, is by far, your best choice to observe and enjoy the species considered by many, as the most beautiful bird in the world.","breadcrumb":{"@id":"https:\/\/www.elmiradordequetzales.com\/en\/tours\/quetzals-tour\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.elmiradordequetzales.com\/en\/tours\/quetzals-tour\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.elmiradordequetzales.com\/en\/tours\/quetzals-tour\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.elmiradordequetzales.com\/en\/"},{"@type":"ListItem","position":2,"name":"Tours","item":"https:\/\/www.elmiradordequetzales.com\/en\/tours\/"},{"@type":"ListItem","position":3,"name":"Quetzal\u2019s Tour"}]}]}},"_links":{"self":[{"href":"https:\/\/www.elmiradordequetzales.com\/en\/wp-json\/wp\/v2\/pages\/2003"}],"collection":[{"href":"https:\/\/www.elmiradordequetzales.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.elmiradordequetzales.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.elmiradordequetzales.com\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.elmiradordequetzales.com\/en\/wp-json\/wp\/v2\/comments?post=2003"}],"version-history":[{"count":20,"href":"https:\/\/www.elmiradordequetzales.com\/en\/wp-json\/wp\/v2\/pages\/2003\/revisions"}],"predecessor-version":[{"id":2495,"href":"https:\/\/www.elmiradordequetzales.com\/en\/wp-json\/wp\/v2\/pages\/2003\/revisions\/2495"}],"up":[{"embeddable":true,"href":"https:\/\/www.elmiradordequetzales.com\/en\/wp-json\/wp\/v2\/pages\/2031"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.elmiradordequetzales.com\/en\/wp-json\/wp\/v2\/media\/2349"}],"wp:attachment":[{"href":"https:\/\/www.elmiradordequetzales.com\/en\/wp-json\/wp\/v2\/media?parent=2003"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}